{"id":3181,"date":"2024-11-29T11:46:01","date_gmt":"2024-11-29T11:46:01","guid":{"rendered":"https://www.atls-global.com/ca/?page_id=3181"},"modified":"2024-11-29T11:57:46","modified_gmt":"2024-11-29T11:57:46","slug":"condiciones-de-contratacion-hub","status":"publish","type":"page","link":"https://www.atls-global.com/ca/condiciones-de-contratacion-hub/","title":{"rendered":"Condiciones de contratacion HUB"},"content":{"rendered":"\r\n<div id=\"\" class=\"cabecera-formulario form_blue block\"\r\nstyle=\"\r\n    background-color: #03577b;\r\n    background: linear-gradient(50deg, #03577b 2%, #242424 100%);\r\n\">\r\n\r\n    <div class=\"texture_bg\">\r\n        <div class=\"bg_image\"></div>\r\n        <div class=\"texture\"><img decoding=\"async\" src=\"https://atls-global.com/wp-content/themes/atls_global/assets/atls_texture.png\" alt=\"ATLS texture\"></div>\r\n    </div>\r\n\r\n    <div class=\"site_width XL\">\r\n        \r\n        <div class=\"cols\">\r\n\r\n            <div class=\"col left\">\r\n                <h1>Condiciones de contratacion HUB</h1>\r\n                <div class=\"descripcion parrafo_medio\">\r\n                                    </div>\r\n                            </div>\r\n            <div class=\"col right\">\r\n                            </div>\r\n\r\n        </div>\r\n\r\n    </div>\r\n\r\n</div>\n\n\r\n<div id=\"jSfLbD\" class=\"texto-columnas straight_top block\"\r\nstyle=\"\r\n    background-color: ;\r\n\">\r\n\r\n    \r\n    <div class=\"site_width XL padding_wrapper\">\r\n\r\n        \r\n                    <div class=\"texto one_cols\">\r\n                <p><b>Información previa al proceso contractual</b><br />\nLa presente página web&nbsp;<a href=\"https://hub.at-ls.com/\" data-type=\"URL\" data-id=\"https://hub.at-ls.com/\" target=\"_blank\" rel=\"noopener\">http://www.hub.at-ls.com</a>&nbsp;es propiedad de ATLS GLOBAL, SL con CIF B62026430 y dirección fiscal en Via Augusta, 13-15, 2ª planta, oficina 203, 08006, BARCELONA, actuando comercialmente bajo la marca ATLS.</p>\n<p>Las condiciones Generales de Contratación regulan la relación de venta a distancia entre ATLS GLOBAL, SL y el usuario o cliente, de acuerdo con las estipulaciones legales, en especial, la Ley 7/1998, de 13 de abril, sobre Condiciones Generales de Contratación, la Ley 3/2014, de 27 de marzo por la que se modifica el texto refundido de la Ley General para la Defensa de los consumidores y Usuarios, la Ley Orgánica 15/1999, de 13 de diciembre, de Protección de Datos de Carácter Personal, la Ley 7/1996, de 15 de enero de Ordenación del Comercio Minorista, y a la Ley 34/2002 de 11 de julio, de Servicios de la Sociedad de la Información y de Comercio Electrónico.</p>\n<p>ATLS GLOBAL, SL se reserva el derecho a realizar las modificaciones que considere oportunas, sin aviso previo, en las condiciones generales. Dichas modificaciones podrán realizarse, a través de sus websites, por cualquier forma admisible en derecho y serán de obligado cumplimiento durante el tiempo en que se encuentren publicadas en la web y hasta que no sean modificadas válidamente por otras posteriores. No obstante, ATLS GLOBAL, SL se reserva el derecho de aplicar, en determinados casos, unas condiciones particulares de contratación con preferencia a las presentes condiciones generales cuando lo considere oportuno, anunciándolas en tiempo y forma oportunos.</p>\n<p>El objeto de la página web es servicios de traducciones de documentos, webs y otros archivos.</p>\n<p>La duración del contrato quedará vinculada a la finalización del servicio contratado.</p>\n<p>Como usuario o cliente declara expresamente conocer, entender y aceptar las condiciones de uso y estas condiciones generales de contratación. Del mismo modo, declara ser mayor de edad y tener la capacidad jurídica y de obrar necesarias para el acceso a los sitios web de ATLS GLOBAL, SL y la contratación por medio de los mismos.</p>\n<p>Para adquirir nuestros servicios, usted puede dirigirse al apartado correspondiente de nuestra tienda online.</p>\n<p>Es requisito imprescindible que se registre como usuario de la web para realizar la compra online. Puede acceder al apartado correspondiente para el registro en la propia web. De conformidad con lo que establece la Ley Orgánica 15/1999 de Protección de Datos de Carácter Personal, ATLS GLOBAL, SL informa a los usuarios que los datos personales recabados durante el proceso de registro y posterior compra, serán introducidos en un fichero bajo su responsabilidad, con la finalidad de tramitar dichas acciones por parte del usuario y gestionar actuaciones posteriores derivadas de las mismas.</p>\n<p>Asimismo, ATLS GLOBAL, SL informa de la posibilidad de ejercer los derechos de acceso, rectificación, cancelación y oposición mediante un escrito a la dirección Via Augusta, 13-15, 2ª planta, oficina 203, 08006, BARCELONA o a través del correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@at-ls.com</a>.</p>\n<p>Mientras no nos comunique lo contrario, entenderemos que sus datos no han sido modificados, que usted se compromete a notificarnos cualquier variación y que tenemos el consentimiento para utilizarlos a fin de poder fidelizar la relación entre las partes.</p>\n<p>Durante el proceso de compra deberá identificarse con el nombre de usuario y la contraseña proporcionados. Estos datos no serán públicos. Usted se hace responsable de tratar confidencial y responsablemente la identidad y contraseña obtenidas en el registro como cliente, no pudiendo cederlas a otro. Puede modificar la información registrada en cualquier momento en su área de cliente. En este mismo apartado usted tendrá acceso a un histórico de sus servicios contratados; este solo es un apartado de consulta pero se permite su gestión, pudiendo el usuario eliminar aquellos registros que considere no es necesario visualizar.</p>\n<p>Finalizado el proceso de compra, el cliente recibirá una confirmación del mismo por correo electrónico. Es imprescindible que durante el proceso de compra el usuario indique un correo electrónico válido. Si en 24 horas desde la finalización del servicio no recibe la confirmación, póngase en contacto con ATLS GLOBAL, SL en el teléfono de atención al cliente 933043138 o mediante el correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@at-ls.com</a>.</p>\n<p>Todos los contenidos de la web se ofrecen en español, English , Deutsch , Français , Italiano, Português , Pусский , 中文 , 日本語 , ال عرب ية , Català , Euskara , Galego.</p>\n<p>Previamente a la prestación del servicio el cliente recibirá un correo electrónico con la confirmación del servicio solicitado.</p>\n<p>Una vez prestado el servicio el cliente recibirá la correspondiente factura. En caso de precisar la expedición de la factura electrónica deberá consentirlo de manera expresa en el procedimiento de compra.</p>\n<p><b>Características, oferta y vigencia de los servicios</b><br />\nLos servicios ofertados en nuestra tienda online se detallan las características esenciales de los mismos.</p>\n<p>En caso de un servicio en oferta, siempre se indicará junto a sus características esenciales el precio de oferta y la validez de la misma.</p>\n<p>En cumplimiento de la normativa vigente ATLS GLOBAL, SL ofrece información sobre todos sus servicios, sus características y precios. No obstante, ATLS GLOBAL, SL se reserva el derecho a retirar, reponer o cambiar los servicios que se ofrecen a través de su página web, mediante el simple cambio en el contenido de la misma. De esta forma, los servicios ofrecidos en cada momento por la web se regirán por las condiciones generales de contratación vigentes en cada momento. Asimismo, la empresa tendrá la facultad de dejar de ofrecer, sin previo aviso y en cualquier momento, el acceso a los servicios mencionados.</p>\n<p><b>Garantías</b><br />\nTodos los servicios ofrecidos en la página web gozan de la garantía correspondiente al tipo de servicio y al tiempo y forma de prestación de servicios que se haya solicitado.</p>\n<p>ATLS GLOBAL, SL dispone de un servicio de atención al cliente, mediante el teléfono 933043138 o el correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@at-ls.com</a>&nbsp;donde podrá dirigir la reclamación correspondiente en caso desconformidad.</p>\n<p><b>Precios</b><br />\nTodos los servicios indican el precio de venta en euros y no incluyen el Impuesto sobre el Valor Añadido (IVA).</p>\n<p>Si fuera aplicable cualquier otro impuesto, así se indicaría (IGIC o IPSI).</p>\n<p><b>Gastos y prestación de los servicios</b><br />\nATLS GLOBAL, SL realiza los servicios en España, Europa y a nivel mundial, cobrando una cantidad específica en euros, GBP, $USD, $AUD, $CAD, $MXN, CHF CHF, $NZD, AED AED, SAR, $SGD, CNY, $HKD, JPY, RUB, QAR en concepto de los gastos derivados del servicio contratado.<br />\nEn todo caso, en la correspondiente factura se detallaran los gastos relativos al servicio contratado.</p>\n<p><b>Formas de pago y ejecución del servicio</b><br />\nEl cliente podrá abonar el importe de su servicio optando por cualquiera de las siguientes formas.<br />\nDurante el proceso de compra deberá indicar su elección:</p>\n<p>–&nbsp;<b>Tarjeta de crédito VISA o MASTERCARD</b><br />\nTodas las operaciones que implican la transmisión de datos personales o bancarios se realizan utilizando un entorno seguro, un servidor basado en la tecnología de seguridad estándar SSL (Secure Sockets Layer). Toda la información que nos transmita viaja cifrada a través de la red.</p>\n<p>Asimismo los datos sobre su tarjeta de crédito son introducidos directamente en la página del banco, en el TPV (Terminal Punto de venta del Banco) y no son introducidos, registrados ni almacenados en ningún servidor de ATLS GLOBAL, SL.</p>\n<p>Al pagar con tarjeta VISA o MASTERCARD se le solicitarán siempre los siguientes datos: el número de tarjeta, la fecha de caducidad, y un código de validación que coincide con las 3 últimas cifras del número impreso en cursiva en el reverso de su tarjeta VISA o MASTERCARD, ofreciendo, de esta forma, más garantías acerca de la seguridad de la transacción.</p>\n<p>Esta forma de pago es válida únicamente en la web.</p>\n<p>Cuando el importe de una compra hubiese sido cargado fraudulenta o indebidamente utilizando el número de una tarjeta de pago, su titular podrá exigir la inmediata anulación del cargo. En tal caso, las correspondientes anotaciones de adeudo y reabono en las cuentas del proveedor y del titular se efectuarán a la mayor brevedad.</p>\n<p>Sin embargo, si la compra hubiese sido efectivamente realizada por el titular de la tarjeta y la exigencia de devolución no fuera consecuencia de haberse ejercido el derecho de desistimiento o de resolución y, por tanto, hubiese exigido indebidamente la anulación del correspondiente cargo, aquel quedará obligado frente a ATLS GLOBAL, SL al resarcimiento de los daños y perjuicios ocasionados como consecuencia de dicha anulación.</p>\n<p>–&nbsp;<b>PayPal</b><br />\nPermite enviar pagos en Internet de forma segura y cómoda. La red de PayPal se basa en la infraestructura financiera existente de cuentas bancarias y tarjetas de crédito para crear una solución global de pago en tiempo real. PayPal ofrece un servicio especialmente pensado para aquellos a los que no les satisfacen los mecanismos de pago tradicionales.</p>\n<p>Más información en PayPal:&nbsp;<a class=\"green\" href=\"http://www.paypal.com/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">http://www.paypal.com</a>.</p>\n<p>ATLS GLOBAL, SL se compromete a prestar el servicio en el periodo de días indicado en el momento de realizar el pedido. Dicho plazo se establecerá atendiendo el idioma, el tipo de traducción y el número de palabras.</p>\n<p>La disponibilidad de servicios ofrecidos por ATLS GLOBAL, SL puede variar en función del servicio. En caso de no ejecución por indisponibilidad, ATLS GLOBAL, SL lo notificará al cliente&nbsp;en el momento que tenga conocimiento de esta situación, por medio de un correo electrónico. El periodo de esta comunicación no superará en ningún caso el plazo máximo de 30 días. ATLS GLOBAL, SL podrá otorgar una de dos opciones: ofrecer al cliente, sin coste adicional, un servicio de características similares o de superior calidad, o previa aportación de razones justificadas y demostrables por parte del cliente, dentro de este mismo periodo abonar las sumas pagadas por el servicio anulado. En el supuesto de que ATLS GLOBAL, SL no realice este abono en el plazo señalado, el comprador podrá reclamar que se le abone el doble de la suma adeudada, sin perjuicio a su derecho de ser indemnizado.</p>\n<p><b>Derecho de desistimiento, reembolso del pago y reclamaciones</b><br />\nEl cliente dispondrá de un plazo mínimo de catorce días naturales para desistir, a partir del día de celebración del contrato, sin penalización alguna y sin indicación de los motivos.</p>\n<p>El ejercicio del derecho de desistimiento deberá realizarse mediante notificación a través comunicación telefónica a 933043138, dirigiéndose al correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@at-ls.com</a>&nbsp;, remitiendo su escrito a nuestra dirección postal Via Augusta, 13-15, 2ª planta, oficina 203, 08006, BARCELONA, o bien a través del&nbsp;<a class=\"green\" href=\"https://www.atls-global.com/ca/modelo-formulario-desestimiento/\" target=\"_blank\" rel=\"noopener noreferrer\">formulario de desistimiento</a>.</p>\n<p>Según lo establecido el artículo 103 de la Ley 3/2014, de 27 de marzo por la que se modifica el texto refundido de la Ley General para la Defensa de los Consumidores y Usuarios, los suministros de servicios o bienes confeccionado conforme a las especificaciones del consumidor o claramente personalizados, o que, por su naturaleza, no puedan ser devueltos o puedan deteriorarse o caducar con rapidez, están exentos de desistimiento.</p>\n<p>Si el cliente solicita que la prestación del servicio dé comienzo durante el periodo de desistimiento, este quedará obligado al abono del importe proporcional a la parte prestada del servicio en el momento en que haya comunicado su desistimiento, en relación al objeto del contrato.</p>\n<p><b>Reclamación</b><br />\nSi el cliente desea presentar una reclamación, puede hacerlo&nbsp;a través del correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@at-ls.com</a>&nbsp;o bien en persona en el establecimiento de ATLS GLOBAL, SL que está situado en Via Augusta, 13-15, 2ª planta, oficina 203, 08006, BARCELONA .</p>\n<p><b>Jurisdicción</b><br />\nAsimismo, ATLS GLOBAL, SL se reserva la facultad de presentar las acciones civiles o penales que considere oportunas por la utilización indebida de su sitio web y contenidos o por el incumplimiento de las presentes condiciones.</p>\n<p>La relación entre el usuario y el prestador se regirá por la normativa vigente y de aplicación en el territorio español. De surgir cualquier controversia las partes podrán someter sus conflictos a arbitraje o acudir a la jurisdicción ordinaria cumpliendo con las normas sobre jurisdicción y competencia al respecto. ATLS GLOBAL, SL tiene su domicilio en BARCELONA, España.</p>\n<p><strong>Periodos de prueba de los servicios</strong></p>\n<p>El servicio online de traducción web, AT Website Translator, dispone de un período de prueba de un mes, estando limitado por página web.</p>\n<p>Cuando el plazo del período de prueba esté a punto de finalizar, se le notificará al usuario por correo electrónico. Una vez finalizado el período de prueba, el usuario deberá realizar la compra de un plan de pago para seguir teniendo acceso al servicio de traducción web.</p>\n<p>Un usuario que haya disfrutado de un mes de prueba no podrá contratar otro mes de prueba para la misma página web.</p>\n            </div>\r\n        \r\n        \r\n    </div>\r\n\r\n</div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3181","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages"}],"about":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/types/page"}],"author":[{"embeddable":true,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/users/5"}],"replies":[{"embeddable":true,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/comments?post=3181"}],"version-history":[{"count":3,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3181/revisions"}],"predecessor-version":[{"id":3196,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3181/revisions/3196"}],"wp:attachment":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/media?parent=3181"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}