{"id":3197,"date":"2024-11-29T12:01:23","date_gmt":"2024-11-29T12:01:23","guid":{"rendered":"https://www.atls-global.com/ca/?page_id=3197"},"modified":"2024-11-29T12:01:36","modified_gmt":"2024-11-29T12:01:36","slug":"clausulas-legales","status":"publish","type":"page","link":"https://www.atls-global.com/ca/clausulas-legales/","title":{"rendered":"Cláusulas legales"},"content":{"rendered":"\r\n<div id=\"\" class=\"cabecera-formulario form_blue block\"\r\nstyle=\"\r\n    background-color: #4c3b8f;\r\n    background: linear-gradient(50deg, #4c3b8f 2%, #ff3eb5 100%);\r\n\">\r\n\r\n    <div class=\"texture_bg\">\r\n        <div class=\"bg_image\"></div>\r\n        <div class=\"texture\"><img decoding=\"async\" src=\"https://atls-global.com/wp-content/themes/atls_global/assets/atls_texture.png\" alt=\"ATLS texture\"></div>\r\n    </div>\r\n\r\n    <div class=\"site_width XL\">\r\n        \r\n        <div class=\"cols\">\r\n\r\n            <div class=\"col left\">\r\n                <h1>Cláusulas legales</h1>\r\n                <div class=\"descripcion parrafo_medio\">\r\n                                    </div>\r\n                            </div>\r\n            <div class=\"col right\">\r\n                            </div>\r\n\r\n        </div>\r\n\r\n    </div>\r\n\r\n</div>\n\n\r\n<div id=\"CybWny\" class=\"texto-columnas straight_top block\"\r\nstyle=\"\r\n    background-color: ;\r\n\">\r\n\r\n    \r\n    <div class=\"site_width XL padding_wrapper\">\r\n\r\n        \r\n                    <div class=\"texto one_cols\">\r\n                <p>De conformidad con lo establecido en la normativa vigente en Protección de Datos de Carácter Personal, le informamos que sus datos serán incorporados al sistema de tratamiento titularidad de ATLS Global, S.L. con CIF B62026430 y domicilio social sito en Via Augusta, 13-15, 2ª planta, oficina 203, 08006, BARCELONA, con la finalidad de atender sus consultas y remitirle comunicaciones comerciales que puedan ser de su interés.</p>\n<p>En cumplimiento con la normativa vigente, ATLS Global, S.L. informa que los datos serán conservados durante el plazo estrictamente necesario para cumplir con los preceptos mencionados con anterioridad. Mientras no nos comunique lo contrario, entenderemos que sus datos no han sido modificados, que usted se compromete a notificarnos cualquier variación y que tenemos su consentimiento para utilizarlos para las finalidades mencionadas.</p>\n<p>ATLS Global, S.L. informa que procederá a tratar los datos de manera lícita, leal, transparente, adecuada, pertinente, limitada, exacta y actualizada. Es por ello que ATLS Global, S.L. se compromete a adoptar todas las medidas razonables para que estos se supriman o rectifiquen sin dilación cuando sean inexactos.</p>\n<p>De acuerdo con los derechos que le confiere el la normativa vigente en protección de datos podrá ejercer los derechos de acceso, rectificación, limitación de tratamiento, supresión, portabilidad y oposición al tratamiento de sus datos de carácter personal así como del consentimiento prestado para el tratamiento de los mismos, dirigiendo su petición a la dirección postal indicada más arriba o al correo electrónico&nbsp;<a href=\"mailto:info@at-ls.com\">info@at-ls.com</a>.</p>\n<p>Asimismo y de acuerdo con lo establecido en la Ley 34/2002, de 11 de julio, de Servicios de la Sociedad de la Información y de Comercio Electrónico, en su artículo 21, solicitamos también su consentimiento expreso para enviarle publicidad de nuestros productos o promociones que consideremos puedan ser de su interés, por correo electrónico o por cualquier otro medio de comunicación electrónica equivalente.</p>\n<p>Le informamos que podrá revocar en cualquier momento el consentimiento prestado a la recepción de comunicaciones comerciales enviando un e-mail a la dirección de correo electrónico:&nbsp;<a href=\"mailto:info@at-ls.com?Subject=Revocaci%C3%B3n%20del%20consentimiento%20para%20recibir%20promociones\">info@at-ls.com</a>. Podrá dirigirse a la autoridad de control competente para presentar la reclamación que considere oportuna.</p>\n            </div>\r\n        \r\n        \r\n    </div>\r\n\r\n</div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3197","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages"}],"about":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/types/page"}],"author":[{"embeddable":true,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/users/5"}],"replies":[{"embeddable":true,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/comments?post=3197"}],"version-history":[{"count":1,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3197/revisions"}],"predecessor-version":[{"id":3198,"href":"https://www.atls-global.com/ca/wp-json/wp/v2/pages/3197/revisions/3198"}],"wp:attachment":[{"href":"https://www.atls-global.com/ca/wp-json/wp/v2/media?parent=3197"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}