{"id":3188,"date":"2024-11-29T11:53:37","date_gmt":"2024-11-29T11:53:37","guid":{"rendered":"https://www.atls-global.com/en/?page_id=3188"},"modified":"2024-11-29T11:54:42","modified_gmt":"2024-11-29T11:54:42","slug":"condiciones-generales-de-devolucion","status":"publish","type":"page","link":"https://www.atls-global.com/en/condiciones-generales-de-devolucion/","title":{"rendered":"Condiciones generales de devolución de HUB"},"content":{"rendered":"\r\n<div id=\"\" class=\"cabecera-formulario form_blue block\"\r\nstyle=\"\r\n    background-color: #03577b;\r\n    background: linear-gradient(50deg, #03577b 2%, #242424 100%);\r\n\">\r\n\r\n    <div class=\"texture_bg\">\r\n        <div class=\"bg_image\"></div>\r\n        <div class=\"texture\"><img decoding=\"async\" src=\"https://atls-global.com/wp-content/themes/atls_global/assets/atls_texture.png\" alt=\"ATLS texture\"></div>\r\n    </div>\r\n\r\n    <div class=\"site_width XL\">\r\n        \r\n        <div class=\"cols\">\r\n\r\n            <div class=\"col left\">\r\n                <h1>Condiciones generales de devolucion de HUB</h1>\r\n                <div class=\"descripcion parrafo_medio\">\r\n                                    </div>\r\n                            </div>\r\n            <div class=\"col right\">\r\n                            </div>\r\n\r\n        </div>\r\n\r\n    </div>\r\n\r\n</div>\n\n\r\n<div id=\"YzFhzo\" class=\"texto-columnas straight_top block\"\r\nstyle=\"\r\n    background-color: ;\r\n\">\r\n\r\n    \r\n    <div class=\"site_width XL padding_wrapper\">\r\n\r\n        \r\n                    <div class=\"texto one_cols\">\r\n                <p>Las presentes condiciones generales están sujetas a lo dispuesto en la ley 3/2014, de 27 de marzo, por la que se modifica el texto refundido de la ley general para la defensa de los consumidores y usuarios y otras leyes complementarias, aprobado por el Real Decreto legislativo 1/2007, de 16 de noviembre (B.O.E. 30-11-2007).</p>\n<p>La empresa ATLS GLOBAL, SL, con domicilio en Vía Augusta, número 13-15, 2ª planta, OFICINA 203,&nbsp; 08006, Barcelona con C.I.F. B-62026430 e inscrita en el Registro Mercantil de Barcelona Tomo 31959, Folio 136, Hoja B-202548 inscripción 1ª.</p>\n<p>La política de cancelaciones del servicio de traducciones es la siguiente:<br />\nAT Language Solutions, a su exclusivo criterio, aceptará la cancelación del servicio el mismo día de la fecha de compra del servicio.</p>\n<h2 class=\"wp-block-heading\">Definición de cancelaciones:</h2>\n<p>Si un cliente solicita una devolución, una vez revisada la solicitud por parte de ATLS GLOBAL, SL, en caso de resolver la cancelación del servicio, el dinero de la transacción solicitada se reembolsa al cliente mediante transferencia bancaria, devolución del importe a su tarjeta de crédito o débito o mediante reembolso en la cuenta PayPal del cliente.</p>\n<h2 class=\"wp-block-heading\">Detalles de la política de cancelación del servicio de traducción:</h2>\n<p>Los clientes que solicitan una cancelación del servicio de traducción serán remitidos al personal de atención para que reciban soporte técnico o servicio de atención al cliente. Las devoluciones solo se acreditarán en la cuenta que se usó para realizar la compra original. Si la cuenta original se cerró, la compra no reúne los requisitos para devoluciones.</p>\n<h2 class=\"wp-block-heading\">Motivos por los que un servicio de traducción puede reembolsarse:</h2>\n<p>Para garantizar la satisfacción del cliente, ATLS GLOBAL, SL se reserva el derecho de revertir una venta, incluyendo, entre otras, los siguientes motivos:</p>\n<ol class=\"wp-block-list\">\n<li>Si el cliente presenta una razón válida para solicitar una devolución dentro de los 10 días posteriores a la compra del servicio.</li>\n<li>Si nuestro equipo del servicio de atención al cliente confirma que existe una razón válida para la devolución.</li>\n<li>Si el cliente presenta un informe válido de que el cobro fue fraudulento o no autorizado.</li>\n<li>Para cumplir con los términos de servicio de PayPal, la ley española y las solicitudes de fuerzas públicas legales o judiciales españolas verificadas o por cualquier motivo que ATLS GLOBAL, SL considere apropiado.</li>\n</ol>\n<h2 class=\"wp-block-heading\">Abuso de la política de cancelaciones:</h2>\n<p>A los clientes que soliciten devoluciones repetidas o consecutivas se les puede impedir la realización de futuras compras.</p>\n<h2 class=\"wp-block-heading\">Observación para clientes de ATLS:</h2>\n<p>Como condición para la inscripción en ATLS GLOBAL, SL y el uso de los servicios de ATLS GLOBAL, SL, usted expresamente reconoce que ha leído y comprendido esta política de devoluciones y cancelaciones, y acepta quedar obligado por los términos y condiciones allí contenidos. Si en cualquier momento usted deja de estar de acuerdo con esta política de devoluciones y cancelaciones o cualquier parte de ésta, su único recurso es interrumpir el uso de los servicios de AT Language Solutions y cerrar su cuenta. No obstante, tenga en cuenta que toda transacción que hubiera ocurrido antes de la fecha de dicho cierre se regirá y estará controlada en su totalidad por los términos de esta política de devoluciones y cancelaciones.</p>\n            </div>\r\n        \r\n        \r\n    </div>\r\n\r\n</div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3188","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https://www.atls-global.com/en/wp-json/wp/v2/pages/3188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.atls-global.com/en/wp-json/wp/v2/pages"}],"about":[{"href":"https://www.atls-global.com/en/wp-json/wp/v2/types/page"}],"author":[{"embeddable":true,"href":"https://www.atls-global.com/en/wp-json/wp/v2/users/5"}],"replies":[{"embeddable":true,"href":"https://www.atls-global.com/en/wp-json/wp/v2/comments?post=3188"}],"version-history":[{"count":3,"href":"https://www.atls-global.com/en/wp-json/wp/v2/pages/3188/revisions"}],"predecessor-version":[{"id":3192,"href":"https://www.atls-global.com/en/wp-json/wp/v2/pages/3188/revisions/3192"}],"wp:attachment":[{"href":"https://www.atls-global.com/en/wp-json/wp/v2/media?parent=3188"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}